{"id":4545,"date":"2025-03-05T09:20:12","date_gmt":"2025-03-05T09:20:12","guid":{"rendered":"https:\/\/irotec.wisefrog.eu\/regios\/"},"modified":"2026-06-25T11:45:23","modified_gmt":"2026-06-25T11:45:23","slug":"regios","status":"publish","type":"page","link":"https:\/\/test.irotec.nl\/nl\/regios\/","title":{"rendered":"Locaties"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; custom_padding_last_edited=&#8221;on|phone&#8221; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; background_image=&#8221;https:\/\/test.irotec.nl\/wp-content\/uploads\/2026\/06\/DSC1525-scaled.jpg&#8221; custom_padding=&#8221;395px||103px||false|false&#8221; custom_padding_tablet=&#8221;55px||38px||false|false&#8221; custom_padding_phone=&#8221;34px||38px||false|false&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row column_structure=&#8221;2_5,3_5&#8243; use_custom_gutter=&#8221;on&#8221; module_class=&#8221;cus-row&#8221; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; width=&#8221;90%&#8221; custom_padding=&#8221;0px||0px||false|false&#8221; custom_css_main_element=&#8221;display:flex;||flex-wrap:wrap;&#8221; custom_css_free_form=&#8221;@media(max-width:1024px){||  selector.cus-row{||   display:block !important;||  }||}||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;2_5&#8243; module_class=&#8221;cus-col&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_css_main_element=&#8221;align-self:flex-end;&#8221; custom_css_free_form=&#8221;@media(max-width:1024px){||  selector.cus-col{||    width:100% !important;||  }||}||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Host Grotesk|500|||||||&#8221; text_text_color=&#8221;#ffffff&#8221; text_font_size=&#8221;22px&#8221; text_line_height=&#8221;33px&#8221; header_font=&#8221;Host Grotesk|600|||||||&#8221; header_text_color=&#8221;#ffffff&#8221; header_font_size=&#8221;88px&#8221; header_line_height=&#8221;96px&#8221; header_2_font=&#8221;Host Grotesk|700|||||||&#8221; header_2_text_align=&#8221;left&#8221; header_2_text_color=&#8221;#000000&#8243; header_2_font_size=&#8221;72px&#8221; header_2_line_height=&#8221;79px&#8221; header_3_font=&#8221;Host Grotesk|700|||||||&#8221; header_3_font_size=&#8221;32px&#8221; header_3_line_height=&#8221;41px&#8221; custom_margin=&#8221;||0px||false|false&#8221; custom_margin_phone=&#8221;||20px||false|false&#8221; custom_margin_last_edited=&#8221;off|desktop&#8221; custom_padding=&#8221;||0px||false|false&#8221; text_font_size_tablet=&#8221;18px&#8221; text_font_size_phone=&#8221;16px&#8221; text_font_size_last_edited=&#8221;on|phone&#8221; text_line_height_tablet=&#8221;26px&#8221; text_line_height_phone=&#8221;24px&#8221; text_line_height_last_edited=&#8221;on|tablet&#8221; header_font_size_tablet=&#8221;60px&#8221; header_font_size_phone=&#8221;40px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; header_line_height_tablet=&#8221;70px&#8221; header_line_height_phone=&#8221;50px&#8221; header_line_height_last_edited=&#8221;on|tablet&#8221; header_2_font_size_tablet=&#8221;60px&#8221; header_2_font_size_phone=&#8221;40px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; header_2_line_height_tablet=&#8221;70px&#8221; header_2_line_height_phone=&#8221;50px&#8221; header_2_line_height_last_edited=&#8221;on|tablet&#8221; header_3_font_size_tablet=&#8221;&#8221; header_3_font_size_phone=&#8221;26px&#8221; header_3_font_size_last_edited=&#8221;on|tablet&#8221; header_3_line_height_tablet=&#8221;&#8221; header_3_line_height_phone=&#8221;36px&#8221; header_3_line_height_last_edited=&#8221;on|tablet&#8221; header_4_font_size_tablet=&#8221;&#8221; header_4_font_size_phone=&#8221;&#8221; header_4_font_size_last_edited=&#8221;on|phone&#8221; header_4_line_height_tablet=&#8221;&#8221; header_4_line_height_phone=&#8221;&#8221; header_4_line_height_last_edited=&#8221;on|tablet&#8221; header_5_font_size_tablet=&#8221;&#8221; header_5_font_size_phone=&#8221;&#8221; header_5_font_size_last_edited=&#8221;on|phone&#8221; header_5_line_height_tablet=&#8221;&#8221; header_5_line_height_phone=&#8221;&#8221; header_5_line_height_last_edited=&#8221;on|tablet&#8221; header_6_font_size_tablet=&#8221;&#8221; header_6_font_size_phone=&#8221;&#8221; header_6_font_size_last_edited=&#8221;on|tablet&#8221; header_6_line_height_tablet=&#8221;&#8221; header_6_line_height_phone=&#8221;&#8221; header_6_line_height_last_edited=&#8221;on|phone&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]Wij bieden met trots deskundige ongediertebestrijdingsoplossingen aan op meerdere locaties. Ontdek hoe wij kunnen helpen om uw huis of bedrijf in uw regio vrij van ongedierte te houden.[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;3_5&#8243; module_class=&#8221;cus-col&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; background_image=&#8221;https:\/\/test.irotec.nl\/wp-content\/uploads\/2025\/03\/Component-Titles-1.png&#8221; custom_padding=&#8221;60px|62px|60px|62px|true|true&#8221; custom_padding_tablet=&#8221;40px|50px|40px|50px|true|true&#8221; custom_padding_phone=&#8221;28px|20px|28px|20px|true|true&#8221; custom_padding_last_edited=&#8221;on|phone&#8221; custom_css_main_element=&#8221;align-self:flex-end;||backdrop-filter:blur(10px);&#8221; custom_css_free_form=&#8221;@media(max-width:1024px){||  selector.cus-col{||    width:100% !important;||    margin-bottom:32px !important;||  }||}||@media(max-width:768px){||  selector.cus-col{||    margin-bottom:24px !important;||  }||}&#8221; border_radii=&#8221;on|28px|28px|28px|28px&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Host Grotesk||||||||&#8221; text_text_color=&#8221;#2e2e2e&#8221; text_line_height=&#8221;32px&#8221; header_font=&#8221;Host Grotesk|600|||||||&#8221; header_text_color=&#8221;#ffffff&#8221; header_font_size=&#8221;80px&#8221; header_line_height=&#8221;96px&#8221; header_2_font=&#8221;Host Grotesk|600|||||||&#8221; header_2_text_align=&#8221;left&#8221; header_2_text_color=&#8221;#000000&#8243; header_2_font_size=&#8221;72px&#8221; header_2_line_height=&#8221;79px&#8221; header_3_font=&#8221;Host Grotesk|700|||||||&#8221; header_3_font_size=&#8221;32px&#8221; header_3_line_height=&#8221;41px&#8221; header_4_font=&#8221;Host Grotesk|600|||||||&#8221; header_4_font_size=&#8221;22px&#8221; header_4_line_height=&#8221;28px&#8221; header_5_font=&#8221;Host Grotesk||||||||&#8221; header_5_font_size=&#8221;19px&#8221; header_5_line_height=&#8221;24px&#8221; max_width=&#8221;700px&#8221; max_width_tablet=&#8221;100%&#8221; max_width_phone=&#8221;100%&#8221; max_width_last_edited=&#8221;on|tablet&#8221; custom_margin=&#8221;||0px||false|false&#8221; custom_margin_phone=&#8221;||20px||false|false&#8221; custom_margin_last_edited=&#8221;off|desktop&#8221; custom_padding=&#8221;||0px||false|false&#8221; custom_padding_tablet=&#8221;||||false|false&#8221; custom_padding_phone=&#8221;||||false|false&#8221; custom_padding_last_edited=&#8221;on|phone&#8221; text_font_size_tablet=&#8221;18px&#8221; text_font_size_phone=&#8221;16px&#8221; text_font_size_last_edited=&#8221;on|phone&#8221; text_line_height_tablet=&#8221;26px&#8221; text_line_height_phone=&#8221;24px&#8221; text_line_height_last_edited=&#8221;on|tablet&#8221; header_font_size_tablet=&#8221;60px&#8221; header_font_size_phone=&#8221;40px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; header_line_height_tablet=&#8221;70px&#8221; header_line_height_phone=&#8221;50px&#8221; header_line_height_last_edited=&#8221;on|tablet&#8221; header_2_font_size_tablet=&#8221;60px&#8221; header_2_font_size_phone=&#8221;40px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; header_2_line_height_tablet=&#8221;70px&#8221; header_2_line_height_phone=&#8221;50px&#8221; header_2_line_height_last_edited=&#8221;on|tablet&#8221; header_3_font_size_tablet=&#8221;&#8221; header_3_font_size_phone=&#8221;26px&#8221; header_3_font_size_last_edited=&#8221;on|tablet&#8221; header_3_line_height_tablet=&#8221;&#8221; header_3_line_height_phone=&#8221;36px&#8221; header_3_line_height_last_edited=&#8221;on|tablet&#8221; header_4_font_size_tablet=&#8221;18px&#8221; header_4_font_size_phone=&#8221;26px&#8221; header_4_font_size_last_edited=&#8221;on|phone&#8221; header_4_line_height_tablet=&#8221;26px&#8221; header_4_line_height_phone=&#8221;36px&#8221; header_4_line_height_last_edited=&#8221;on|tablet&#8221; header_5_font_size_tablet=&#8221;&#8221; header_5_font_size_phone=&#8221;&#8221; header_5_font_size_last_edited=&#8221;on|phone&#8221; header_5_line_height_tablet=&#8221;30px&#8221; header_5_line_height_phone=&#8221;25px&#8221; header_5_line_height_last_edited=&#8221;off|desktop&#8221; header_6_font_size_tablet=&#8221;22px&#8221; header_6_font_size_phone=&#8221;18px&#8221; header_6_font_size_last_edited=&#8221;off|desktop&#8221; header_6_line_height_tablet=&#8221;25px&#8221; header_6_line_height_phone=&#8221;22px&#8221; header_6_line_height_last_edited=&#8221;off|desktop&#8221; custom_css_free_form=&#8221;selector h1{||  padding-bottom:0px;||}&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1>Bekijk de regio\u2019s waar wij actief zijn<\/h1>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; custom_padding_last_edited=&#8221;on|tablet&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#f4f6fd&#8221; custom_padding=&#8221;180px||95px||false|false&#8221; custom_padding_tablet=&#8221;70px||40px||false|false&#8221; custom_padding_phone=&#8221;50px||30px||false|false&#8221; saved_tabs=&#8221;all&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; width=&#8221;90%&#8221; custom_padding=&#8221;0px||0px||true|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text module_class=&#8221;list-text&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Host Grotesk||||||||&#8221; text_text_color=&#8221;#15171e&#8221; text_line_height=&#8221;32px&#8221; header_font=&#8221;Host Grotesk|600|||||||&#8221; header_text_align=&#8221;center&#8221; header_text_color=&#8221;#ffffff&#8221; header_font_size=&#8221;88px&#8221; header_line_height=&#8221;96px&#8221; header_2_font=&#8221;Host Grotesk|600|||||||&#8221; header_2_text_align=&#8221;center&#8221; header_2_text_color=&#8221;#000000&#8243; header_2_font_size=&#8221;64px&#8221; header_2_line_height=&#8221;77px&#8221; header_3_font=&#8221;Host Grotesk|700|||||||&#8221; header_3_font_size=&#8221;32px&#8221; header_3_line_height=&#8221;41px&#8221; header_4_font=&#8221;Host Grotesk|600|||||||&#8221; header_4_text_color=&#8221;#15171e&#8221; header_4_font_size=&#8221;22px&#8221; header_4_line_height=&#8221;28px&#8221; header_5_font=&#8221;Host Grotesk|600|||||||&#8221; header_5_text_color=&#8221;#15171e&#8221; header_5_font_size=&#8221;19px&#8221; header_5_line_height=&#8221;24px&#8221; text_orientation=&#8221;center&#8221; max_width=&#8221;610px&#8221; max_width_tablet=&#8221;100%&#8221; max_width_phone=&#8221;100%&#8221; max_width_last_edited=&#8221;on|tablet&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;||0px||false|false&#8221; custom_margin_phone=&#8221;||20px||false|false&#8221; custom_margin_last_edited=&#8221;off|desktop&#8221; custom_padding=&#8221;||||false|false&#8221; text_font_size_tablet=&#8221;18px&#8221; text_font_size_phone=&#8221;16px&#8221; text_font_size_last_edited=&#8221;on|desktop&#8221; text_line_height_tablet=&#8221;&#8221; text_line_height_phone=&#8221;&#8221; text_line_height_last_edited=&#8221;on|tablet&#8221; header_font_size_tablet=&#8221;60px&#8221; header_font_size_phone=&#8221;40px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; header_line_height_tablet=&#8221;70px&#8221; header_line_height_phone=&#8221;50px&#8221; header_line_height_last_edited=&#8221;on|tablet&#8221; header_2_font_size_tablet=&#8221;60px&#8221; header_2_font_size_phone=&#8221;40px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; header_2_line_height_tablet=&#8221;70px&#8221; header_2_line_height_phone=&#8221;50px&#8221; header_2_line_height_last_edited=&#8221;on|tablet&#8221; header_3_font_size_tablet=&#8221;&#8221; header_3_font_size_phone=&#8221;26px&#8221; header_3_font_size_last_edited=&#8221;on|phone&#8221; header_3_line_height_tablet=&#8221;&#8221; header_3_line_height_phone=&#8221;36px&#8221; header_3_line_height_last_edited=&#8221;on|tablet&#8221; header_4_font_size_tablet=&#8221;18px&#8221; header_4_font_size_phone=&#8221;&#8221; header_4_font_size_last_edited=&#8221;on|phone&#8221; header_4_line_height_tablet=&#8221;28px&#8221; header_4_line_height_phone=&#8221;&#8221; header_4_line_height_last_edited=&#8221;on|tablet&#8221; header_5_font_size_tablet=&#8221;&#8221; header_5_font_size_phone=&#8221;16px&#8221; header_5_font_size_last_edited=&#8221;on|phone&#8221; header_5_line_height_tablet=&#8221;&#8221; header_5_line_height_phone=&#8221;24px&#8221; header_5_line_height_last_edited=&#8221;on|tablet&#8221; header_6_font_size_tablet=&#8221;22px&#8221; header_6_font_size_phone=&#8221;18px&#8221; header_6_font_size_last_edited=&#8221;off|desktop&#8221; header_6_line_height_tablet=&#8221;25px&#8221; header_6_line_height_phone=&#8221;22px&#8221; header_6_line_height_last_edited=&#8221;off|desktop&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>Bekijk de regio\u2019s waar wij actief zijn<\/h2>\n<p>[\/et_pb_text][et_pb_text module_class=&#8221;list-text&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Host Grotesk||||||||&#8221; text_text_color=&#8221;#15171e&#8221; text_font_size=&#8221;18px&#8221; text_line_height=&#8221;30px&#8221; header_font=&#8221;Host Grotesk|600|||||||&#8221; header_text_align=&#8221;center&#8221; header_text_color=&#8221;#ffffff&#8221; header_font_size=&#8221;88px&#8221; header_line_height=&#8221;96px&#8221; header_2_font=&#8221;Host Grotesk|600|||||||&#8221; header_2_text_align=&#8221;center&#8221; header_2_text_color=&#8221;#000000&#8243; header_2_font_size=&#8221;72px&#8221; header_2_line_height=&#8221;79px&#8221; header_3_font=&#8221;Host Grotesk|700|||||||&#8221; header_3_font_size=&#8221;32px&#8221; header_3_line_height=&#8221;41px&#8221; header_4_font=&#8221;Host Grotesk|600|||||||&#8221; header_4_text_color=&#8221;#15171e&#8221; header_4_font_size=&#8221;22px&#8221; header_4_line_height=&#8221;28px&#8221; header_5_font=&#8221;Host Grotesk|600|||||||&#8221; header_5_text_color=&#8221;#15171e&#8221; header_5_font_size=&#8221;19px&#8221; header_5_line_height=&#8221;24px&#8221; text_orientation=&#8221;center&#8221; max_width=&#8221;454px&#8221; max_width_tablet=&#8221;100%&#8221; max_width_phone=&#8221;100%&#8221; max_width_last_edited=&#8221;on|tablet&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;||0px||false|false&#8221; custom_margin_phone=&#8221;||20px||false|false&#8221; custom_margin_last_edited=&#8221;off|desktop&#8221; custom_padding=&#8221;||||false|false&#8221; text_font_size_tablet=&#8221;18px&#8221; text_font_size_phone=&#8221;16px&#8221; text_font_size_last_edited=&#8221;on|phone&#8221; text_line_height_tablet=&#8221;26px&#8221; text_line_height_phone=&#8221;24px&#8221; text_line_height_last_edited=&#8221;on|tablet&#8221; header_font_size_tablet=&#8221;60px&#8221; header_font_size_phone=&#8221;40px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; header_line_height_tablet=&#8221;70px&#8221; header_line_height_phone=&#8221;50px&#8221; header_line_height_last_edited=&#8221;on|tablet&#8221; header_2_font_size_tablet=&#8221;60px&#8221; header_2_font_size_phone=&#8221;40px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; header_2_line_height_tablet=&#8221;70px&#8221; header_2_line_height_phone=&#8221;50px&#8221; header_2_line_height_last_edited=&#8221;on|tablet&#8221; header_3_font_size_tablet=&#8221;&#8221; header_3_font_size_phone=&#8221;26px&#8221; header_3_font_size_last_edited=&#8221;on|phone&#8221; header_3_line_height_tablet=&#8221;&#8221; header_3_line_height_phone=&#8221;36px&#8221; header_3_line_height_last_edited=&#8221;on|tablet&#8221; header_4_font_size_tablet=&#8221;18px&#8221; header_4_font_size_phone=&#8221;&#8221; header_4_font_size_last_edited=&#8221;on|phone&#8221; header_4_line_height_tablet=&#8221;28px&#8221; header_4_line_height_phone=&#8221;&#8221; header_4_line_height_last_edited=&#8221;on|tablet&#8221; header_5_font_size_tablet=&#8221;&#8221; header_5_font_size_phone=&#8221;16px&#8221; header_5_font_size_last_edited=&#8221;on|phone&#8221; header_5_line_height_tablet=&#8221;&#8221; header_5_line_height_phone=&#8221;24px&#8221; header_5_line_height_last_edited=&#8221;on|tablet&#8221; header_6_font_size_tablet=&#8221;22px&#8221; header_6_font_size_phone=&#8221;18px&#8221; header_6_font_size_last_edited=&#8221;off|desktop&#8221; header_6_line_height_tablet=&#8221;25px&#8221; header_6_line_height_phone=&#8221;22px&#8221; header_6_line_height_last_edited=&#8221;off|desktop&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Onze technici staan voor u klaar in de volgende regio\u2019s<\/p>\n<p>[\/et_pb_text][et_pb_button button_url=&#8221;#cityname&#8221; button_text=&#8221;Vind een specialist bij u in de buurt&#8221; button_alignment=&#8221;center&#8221; disabled_on=&#8221;on|on|on&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; custom_button=&#8221;on&#8221; button_text_size=&#8221;22px&#8221; button_text_color=&#8221;#FFFFFF&#8221; button_bg_color=&#8221;#f74d4e&#8221; button_border_width=&#8221;0px&#8221; button_border_radius=&#8221;50px&#8221; button_font=&#8221;Host Grotesk|500|||||||&#8221; button_use_icon=&#8221;off&#8221; custom_margin=&#8221;50px||0px||false|false&#8221; custom_margin_tablet=&#8221;40px||||false|false&#8221; custom_margin_phone=&#8221;40px||||false|false&#8221; custom_margin_last_edited=&#8221;on|phone&#8221; custom_padding=&#8221;15px|48px|15px|48px|true|true&#8221; button_text_size_tablet=&#8221;18px&#8221; button_text_size_phone=&#8221;16px&#8221; button_text_size_last_edited=&#8221;on|tablet&#8221; disabled=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_button][et_pb_image src=&#8221;https:\/\/test.irotec.nl\/wp-content\/uploads\/2026\/06\/ChatGPT-Image-9-jun-2026-18_52_43.png&#8221; title_text=&#8221;ChatGPT Image 9 jun 2026, 18_52_43&#8243; align=&#8221;center&#8221; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;|-34px|0px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; custom_padding_last_edited=&#8221;on|phone&#8221; module_id=&#8221;cityname&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#FFFFFF&#8221; custom_padding=&#8221;180px||180px||true|false&#8221; custom_padding_tablet=&#8221;70px||70px||true|false&#8221; custom_padding_phone=&#8221;50px||50px||true|false&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row column_structure=&#8221;2_5,3_5&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; width=&#8221;90%&#8221; custom_padding=&#8221;0px|0px|0px|0px|true|true&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;2_5&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text module_class=&#8221;list-text&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Host Grotesk||||||||&#8221; text_text_color=&#8221;#FFFFFF&#8221; text_line_height=&#8221;32px&#8221; header_font=&#8221;Host Grotesk|600|||||||&#8221; header_text_align=&#8221;center&#8221; header_text_color=&#8221;#ffffff&#8221; header_font_size=&#8221;88px&#8221; header_line_height=&#8221;96px&#8221; header_2_font=&#8221;Host Grotesk|600|||||||&#8221; header_2_text_align=&#8221;left&#8221; header_2_text_color=&#8221;#000000&#8243; header_2_font_size=&#8221;64px&#8221; header_2_line_height=&#8221;77px&#8221; header_3_font=&#8221;Host Grotesk|700|||||||&#8221; header_3_font_size=&#8221;32px&#8221; header_3_line_height=&#8221;41px&#8221; header_4_font=&#8221;Host Grotesk|600|||||||&#8221; header_4_text_color=&#8221;#15171e&#8221; header_4_font_size=&#8221;22px&#8221; header_4_line_height=&#8221;28px&#8221; header_5_font=&#8221;Host Grotesk|600|||||||&#8221; header_5_text_color=&#8221;#15171e&#8221; header_5_font_size=&#8221;19px&#8221; header_5_line_height=&#8221;24px&#8221; text_orientation=&#8221;center&#8221; max_width_tablet=&#8221;100%&#8221; max_width_phone=&#8221;100%&#8221; max_width_last_edited=&#8221;off|desktop&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;||0px||false|false&#8221; custom_margin_phone=&#8221;||20px||false|false&#8221; custom_margin_last_edited=&#8221;off|desktop&#8221; custom_padding=&#8221;||||false|false&#8221; text_font_size_tablet=&#8221;18px&#8221; text_font_size_phone=&#8221;16px&#8221; text_font_size_last_edited=&#8221;on|phone&#8221; text_line_height_tablet=&#8221;&#8221; text_line_height_phone=&#8221;&#8221; text_line_height_last_edited=&#8221;on|tablet&#8221; header_font_size_tablet=&#8221;60px&#8221; header_font_size_phone=&#8221;40px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; header_line_height_tablet=&#8221;70px&#8221; header_line_height_phone=&#8221;50px&#8221; header_line_height_last_edited=&#8221;on|tablet&#8221; header_2_font_size_tablet=&#8221;60px&#8221; header_2_font_size_phone=&#8221;40px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; header_2_line_height_tablet=&#8221;70px&#8221; header_2_line_height_phone=&#8221;50px&#8221; header_2_line_height_last_edited=&#8221;on|tablet&#8221; header_3_font_size_tablet=&#8221;&#8221; header_3_font_size_phone=&#8221;26px&#8221; header_3_font_size_last_edited=&#8221;on|phone&#8221; header_3_line_height_tablet=&#8221;&#8221; header_3_line_height_phone=&#8221;36px&#8221; header_3_line_height_last_edited=&#8221;on|tablet&#8221; header_4_font_size_tablet=&#8221;18px&#8221; header_4_font_size_phone=&#8221;&#8221; header_4_font_size_last_edited=&#8221;on|phone&#8221; header_4_line_height_tablet=&#8221;28px&#8221; header_4_line_height_phone=&#8221;&#8221; header_4_line_height_last_edited=&#8221;on|tablet&#8221; header_5_font_size_tablet=&#8221;&#8221; header_5_font_size_phone=&#8221;16px&#8221; header_5_font_size_last_edited=&#8221;on|phone&#8221; header_5_line_height_tablet=&#8221;&#8221; header_5_line_height_phone=&#8221;24px&#8221; header_5_line_height_last_edited=&#8221;on|tablet&#8221; header_6_font_size_tablet=&#8221;22px&#8221; header_6_font_size_phone=&#8221;18px&#8221; header_6_font_size_last_edited=&#8221;off|desktop&#8221; header_6_line_height_tablet=&#8221;25px&#8221; header_6_line_height_phone=&#8221;22px&#8221; header_6_line_height_last_edited=&#8221;off|desktop&#8221; custom_css_free_form=&#8221;selector h2{||  padding-bottom:0px;||}&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>Provincies<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;3_5&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][\/et_pb_row][et_pb_row custom_padding_last_edited=&#8221;on|tablet&#8221; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; width=&#8221;90%&#8221; custom_padding=&#8221;85px||0px||false|false&#8221; custom_padding_tablet=&#8221;0px||||false|false&#8221; custom_padding_phone=&#8221;0px||||false|false&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_toggle title=&#8221;Noord-Holland&#8221; open_toggle_text_color=&#8221;#15171e&#8221; open_toggle_background_color=&#8221;RGBA(255,255,255,0)&#8221; closed_toggle_background_color=&#8221;RGBA(255,255,255,0)&#8221; icon_color=&#8221;#000000&#8243; toggle_icon=&#8221;&#xf063;||fa||900&#8243; use_icon_font_size=&#8221;on&#8221; open_icon_color=&#8221;#000000&#8243; open_toggle_icon=&#8221;&#xf062;||fa||900&#8243; open_use_icon_font_size=&#8221;on&#8221; module_class=&#8221;toggle-cus&#8221; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; title_text_color=&#8221;#15171e&#8221; title_font=&#8221;Host Grotesk|600|||||||&#8221; title_font_size=&#8221;28px&#8221; title_line_height=&#8221;36px&#8221; body_font=&#8221;Host Grotesk||||||||&#8221; body_text_color=&#8221;#15171e&#8221; body_font_size=&#8221;18px&#8221; body_line_height=&#8221;30px&#8221; custom_margin=&#8221;||0px||false|false&#8221; custom_padding=&#8221;32px||32px||false|false&#8221; title_font_size_tablet=&#8221;28px&#8221; title_font_size_phone=&#8221;24px&#8221; title_font_size_last_edited=&#8221;on|desktop&#8221; title_line_height_tablet=&#8221;30px&#8221; title_line_height_phone=&#8221;28px&#8221; title_line_height_last_edited=&#8221;on|tablet&#8221; body_font_size_tablet=&#8221;18px&#8221; body_font_size_phone=&#8221;16px&#8221; body_font_size_last_edited=&#8221;on|phone&#8221; body_line_height_tablet=&#8221;28px&#8221; body_line_height_phone=&#8221;22px&#8221; body_line_height_last_edited=&#8221;on|tablet&#8221; custom_css_free_form=&#8221;selector.toggle-cus:before{||  content: %22%22;||  position: absolute;||  right: 0;||  top: 0%;||  height: 1px;||  background-color:rgba(0, 0, 0, 0.3);||  background-repeat: no-repeat;||  width: calc(100% &#8211; 420px);||}||selector.toggle-cus:after{||  content: %22%22;||  position: absolute;||  right: 0;||  bottom: 0%;||  height: 1px;||  background-color:rgba(0, 0, 0, 0.3);||  background-repeat: no-repeat;||  width: calc(100% &#8211; 420px);||}||selector.toggle-cus h5{||  padding-left:65px;||}||selector.toggle-cus h5:after{||   content: %22%22;||  position: absolute;||  left: 0;||  bottom: 0%;||  height: 38px;||  width:38px;||  background-repeat: no-repeat;||  background-image:url(%22https:\/\/test.irotec.nl\/wp-content\/uploads\/2025\/03\/loction-icon.png%22);||}||selector.toggle-cus.et_pb_toggle_close  {||  background-image:none;||}||selector.toggle-cus {|| padding-left: 420px;||}||selector.toggle-cus .et_pb_toggle_content{||  padding-top:10px;||}||selector.toggle-cus .et_pb_toggle_content span{||  font-size:26px;||  color:#15171E;||  font-weight:600;||}|| selector.toggle-cus .mb-img{||    display:none !important;||  }||@media(max-width:980px){||  selector.toggle-cus:before{||  width:100%;||}||selector.toggle-cus:after{||  width: 100%;||}||  selector.toggle-cus.et_pb_toggle{|| padding-left: 0px !important;||  background-image:none;||}||  selector.toggle-cus .mb-img{||    display:block !important;||  }||  selector.toggle-cus .et_pb_toggle_content{||  padding-top:20px;||}||}||&#8221; border_width_all=&#8221;0px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Onze ongediertebestrijdingsspecialisten zijn actief in heel Noord-Holland en ondersteunen zowel particuliere als zakelijke klanten in stedelijke, industri\u00eble, kust- en landelijke gebieden. Wij bedienen regelmatig locaties zoals Amsterdam, Haarlem, Alkmaar, Hoorn, Purmerend, Zaanstad, Zaandam, Amstelveen, Hilversum, Beverwijk, IJmuiden, Heerhugowaard, Castricum, Volendam, Edam, evenals omliggende steden en dorpen. <\/p>\n<p>Noord-Holland heeft de afgelopen jaren een toename van ongedierteactiviteit gezien, met name betreffende mieren, vliegen, vlooien en knaagdieren. Hogere temperaturen, dichtbevolkte stedelijke omgevingen, horeca-activiteit en eenvoudige toegang tot voedselbronnen dragen bij aan een hogere ongediertedruk. Tijdens de zomermaanden zien we ook een merkbare stijging van rat-gerelateerde klachten, terwijl knaagdieren in koudere perioden vaak naar binnen trekken op zoek naar warmte, wat het risico op verborgen plagen vergroot.  <\/p>\n<p>Wij ondersteunen regelmatig klanten in sectoren zoals horeca, detailhandel, kantoren, logistiek, voedselbedrijven, woningcorporaties en vastgoedbeheer, waar preventie, snelle reactie en compliancy bijzonder belangrijk zijn.<\/p>\n<p>Staat uw locatie niet in de lijst? Geen zorgen, wij dekken ook kleinere gemeenten en landelijke gebieden in heel Noord-Holland. Neem gewoon contact met ons op en wij bevestigen de beschikbaarheid en de vervolgstappen. <\/p>\n<p>[\/et_pb_toggle][et_pb_toggle title=&#8221;Zuid-Holland&#8221; open_toggle_text_color=&#8221;#15171e&#8221; open_toggle_background_color=&#8221;RGBA(255,255,255,0)&#8221; closed_toggle_background_color=&#8221;RGBA(255,255,255,0)&#8221; icon_color=&#8221;#000000&#8243; toggle_icon=&#8221;&#xf063;||fa||900&#8243; use_icon_font_size=&#8221;on&#8221; open_icon_color=&#8221;#000000&#8243; open_toggle_icon=&#8221;&#xf062;||fa||900&#8243; open_use_icon_font_size=&#8221;on&#8221; module_class=&#8221;toggle-cus&#8221; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; title_text_color=&#8221;#15171e&#8221; title_font=&#8221;Host Grotesk|600|||||||&#8221; title_font_size=&#8221;28px&#8221; title_line_height=&#8221;36px&#8221; body_font=&#8221;Host Grotesk||||||||&#8221; body_text_color=&#8221;#15171e&#8221; body_font_size=&#8221;18px&#8221; body_line_height=&#8221;30px&#8221; custom_margin=&#8221;||0px||false|false&#8221; custom_padding=&#8221;32px||32px||false|false&#8221; title_font_size_tablet=&#8221;28px&#8221; title_font_size_phone=&#8221;24px&#8221; title_font_size_last_edited=&#8221;on|desktop&#8221; title_line_height_tablet=&#8221;30px&#8221; title_line_height_phone=&#8221;28px&#8221; title_line_height_last_edited=&#8221;on|tablet&#8221; body_font_size_tablet=&#8221;18px&#8221; body_font_size_phone=&#8221;16px&#8221; body_font_size_last_edited=&#8221;on|phone&#8221; body_line_height_tablet=&#8221;28px&#8221; body_line_height_phone=&#8221;22px&#8221; body_line_height_last_edited=&#8221;on|tablet&#8221; custom_css_free_form=&#8221;selector.toggle-cus:after{||  content: %22%22;||  position: absolute;||  right: 0;||  bottom: 0%;||  height: 1px;||  background-color:rgba(0, 0, 0, 0.3);||  background-repeat: no-repeat;||  width: calc(100% &#8211; 420px);||}||selector.toggle-cus h5{||  padding-left:65px;||}||selector.toggle-cus h5:after{||   content: %22%22;||  position: absolute;||  left: 0;||  bottom: 0%;||  height: 38px;||  width:38px;||  background-repeat: no-repeat;||  background-image:url(%22https:\/\/test.irotec.nl\/wp-content\/uploads\/2025\/03\/loction-icon.png%22);||}||selector.toggle-cus.et_pb_toggle_close  {||  background-image:none;||}||selector.toggle-cus {|| padding-left: 420px;||}||selector.toggle-cus .et_pb_toggle_content{||  padding-top:10px;||}||selector.toggle-cus .et_pb_toggle_content span{||  font-size:26px;||  color:#15171E;||  font-weight:600;||}|| selector.toggle-cus .mb-img{||    display:none !important;||  }||@media(max-width:980px){||  selector.toggle-cus:before{||  width:100%;||}||selector.toggle-cus:after{||  width: 100%;||}||  selector.toggle-cus.et_pb_toggle{|| padding-left: 0px !important;||  background-image:none;||}||  selector.toggle-cus .mb-img{||    display:block !important;||  }||  selector.toggle-cus .et_pb_toggle_content{||  padding-top:20px;||}||}||&#8221; border_width_all=&#8221;0px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Onze specialisten in ongediertebestrijding zijn actief in heel Zuid-Holland en ondersteunen zowel particuliere als zakelijke klanten in sterk verstedelijkte, industri\u00eble, kust- en agrarische gebieden. Wij bedienen regelmatig locaties zoals Rotterdam, Den Haag, Delft, Leiden, Zoetermeer, Gouda, Alphen aan den Rijn, Schiedam, Vlaardingen, Dordrecht, Spijkenisse, Capelle aan den IJssel, Rijswijk, Voorburg en Leidschendam, evenals de omliggende steden en dorpen. <\/p>\n<p>Zuid-Holland heeft de afgelopen jaren te maken gehad met een toenemende plaagdruk, met name door mieren, vliegen en vlooien. Stijgende temperaturen, een dichte bevolking, horeca-activiteit en eenvoudige toegang tot voedselbronnen dragen allemaal bij aan een hogere plaagactiviteit in zowel woon- als bedrijfsomgevingen. Daarnaast is er groeiende aandacht voor invasieve soorten zoals de Aziatische hoornaar, die een risico vormt voor bestuivende insecten die essentieel zijn voor ecosystemen en landbouw. Vroegtijdige identificatie en verantwoord beheer zijn in deze situaties cruciaal.   <\/p>\n<p>Wij ondersteunen regelmatig klanten in sectoren zoals horeca, detailhandel, kantoren, logistiek, voedselbedrijven, de zorg, woningcorporaties en vastgoedbeheer.<\/p>\n<p>Staat uw locatie er niet bij? Geen zorgen \u2014 wij bedienen ook kleinere gemeenten en landelijke gebieden in heel Zuid-Holland. Neem contact met ons op en wij bevestigen de beschikbaarheid en de meest geschikte vervolgstappen voor uw situatie. <\/p>\n<p>[\/et_pb_toggle][et_pb_toggle title=&#8221;Zeeland&#8221; open_toggle_text_color=&#8221;#15171e&#8221; open_toggle_background_color=&#8221;RGBA(255,255,255,0)&#8221; closed_toggle_background_color=&#8221;RGBA(255,255,255,0)&#8221; icon_color=&#8221;#000000&#8243; toggle_icon=&#8221;&#xf063;||fa||900&#8243; use_icon_font_size=&#8221;on&#8221; open_icon_color=&#8221;#000000&#8243; open_toggle_icon=&#8221;&#xf062;||fa||900&#8243; open_use_icon_font_size=&#8221;on&#8221; module_class=&#8221;toggle-cus&#8221; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; title_text_color=&#8221;#15171e&#8221; title_font=&#8221;Host Grotesk|600|||||||&#8221; title_font_size=&#8221;28px&#8221; title_line_height=&#8221;36px&#8221; body_font=&#8221;Host Grotesk||||||||&#8221; body_text_color=&#8221;#15171e&#8221; body_font_size=&#8221;18px&#8221; body_line_height=&#8221;30px&#8221; custom_margin=&#8221;||0px||false|false&#8221; custom_padding=&#8221;32px||32px||false|false&#8221; title_font_size_tablet=&#8221;28px&#8221; title_font_size_phone=&#8221;24px&#8221; title_font_size_last_edited=&#8221;on|desktop&#8221; title_line_height_tablet=&#8221;30px&#8221; title_line_height_phone=&#8221;28px&#8221; title_line_height_last_edited=&#8221;on|tablet&#8221; body_font_size_tablet=&#8221;18px&#8221; body_font_size_phone=&#8221;16px&#8221; body_font_size_last_edited=&#8221;on|phone&#8221; body_line_height_tablet=&#8221;28px&#8221; body_line_height_phone=&#8221;22px&#8221; body_line_height_last_edited=&#8221;on|tablet&#8221; custom_css_free_form=&#8221;selector.toggle-cus:after{||  content: %22%22;||  position: absolute;||  right: 0;||  bottom: 0%;||  height: 1px;||  background-color:rgba(0, 0, 0, 0.3);||  background-repeat: no-repeat;||  width: calc(100% &#8211; 420px);||}||selector.toggle-cus h5{||  padding-left:65px;||}||selector.toggle-cus h5:after{||   content: %22%22;||  position: absolute;||  left: 0;||  bottom: 0%;||  height: 38px;||  width:38px;||  background-repeat: no-repeat;||  background-image:url(%22https:\/\/test.irotec.nl\/wp-content\/uploads\/2025\/03\/loction-icon.png%22);||}||selector.toggle-cus.et_pb_toggle_close  {||  background-image:none;||}||selector.toggle-cus {|| padding-left: 420px;||}||selector.toggle-cus .et_pb_toggle_content{||  padding-top:10px;||}||selector.toggle-cus .et_pb_toggle_content span{||  font-size:26px;||  color:#15171E;||  font-weight:600;||}|| selector.toggle-cus .mb-img{||    display:none !important;||  }||@media(max-width:980px){||  selector.toggle-cus:before{||  width:100%;||}||selector.toggle-cus:after{||  width: 100%;||}||  selector.toggle-cus.et_pb_toggle{|| padding-left: 0px !important;||  background-image:none;||}||  selector.toggle-cus .mb-img{||    display:block !important;||  }||  selector.toggle-cus .et_pb_toggle_content{||  padding-top:20px;||}||}||&#8221; border_width_all=&#8221;0px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p class=\"isSelectedEnd\">Hoewel wij momenteel geen diensten voor ongediertebestrijding in Zeeland aanbieden, onderzoeken we actief de mogelijkheden om ons werkgebied in de toekomst naar deze provincie uit te breiden. Onze langetermijndoelstelling is om zowel particuliere als zakelijke klanten in heel Zeeland te ondersteunen, waaronder steden en plaatsen zoals Middelburg, Vlissingen, Goes, Terneuzen, Zierikzee, Hulst en omliggende kust- en plattelandsgemeenschappen. <\/p>\n<p class=\"isSelectedEnd\">De combinatie van kustgebieden, landbouwgrond, toeristische activiteit en seizoensgebonden bevolkingsschommelingen in Zeeland kan gunstige omstandigheden cre\u00ebren voor uiteenlopende plaagproblemen. Veelvoorkomende zorgen in de regio zijn onder meer knaagdieren, vliegen, mieren, wespen en andere plaagdieren die gedijen nabij voedselbronnen, afvalruimtes en beschutte gebouwen. <\/p>\n<p class=\"isSelectedEnd\">Naarmate we onze activiteiten verder uitbreiden, streven we ernaar professionele oplossingen voor plaagdierbeheer te bieden die zijn afgestemd op de behoeften van lokale bedrijven, horecagelegenheden, voedselgerelateerde sectoren, vastgoedbeheerders en huiseigenaren in heel Zeeland.<\/p>\n<p>Als u in Zeeland gevestigd bent en ge\u00efnformeerd wilt worden wanneer onze diensten in uw gebied beschikbaar komen, raden we u aan contact met ons op te nemen en uw interesse kenbaar te maken.<\/p>\n<p>[\/et_pb_toggle][et_pb_toggle title=&#8221;Noord-Brabant&#8221; open_toggle_text_color=&#8221;#15171e&#8221; open_toggle_background_color=&#8221;RGBA(255,255,255,0)&#8221; closed_toggle_background_color=&#8221;RGBA(255,255,255,0)&#8221; icon_color=&#8221;#000000&#8243; toggle_icon=&#8221;&#xf063;||fa||900&#8243; use_icon_font_size=&#8221;on&#8221; open_icon_color=&#8221;#000000&#8243; open_toggle_icon=&#8221;&#xf062;||fa||900&#8243; open_use_icon_font_size=&#8221;on&#8221; module_class=&#8221;toggle-cus&#8221; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; title_text_color=&#8221;#15171e&#8221; title_font=&#8221;Host Grotesk|600|||||||&#8221; title_font_size=&#8221;28px&#8221; title_line_height=&#8221;36px&#8221; body_font=&#8221;Host Grotesk||||||||&#8221; body_text_color=&#8221;#15171e&#8221; body_font_size=&#8221;18px&#8221; body_line_height=&#8221;30px&#8221; custom_margin=&#8221;||0px||false|false&#8221; custom_padding=&#8221;32px||32px||false|false&#8221; title_font_size_tablet=&#8221;28px&#8221; title_font_size_phone=&#8221;24px&#8221; title_font_size_last_edited=&#8221;on|desktop&#8221; title_line_height_tablet=&#8221;30px&#8221; title_line_height_phone=&#8221;28px&#8221; title_line_height_last_edited=&#8221;on|tablet&#8221; body_font_size_tablet=&#8221;18px&#8221; body_font_size_phone=&#8221;16px&#8221; body_font_size_last_edited=&#8221;on|phone&#8221; body_line_height_tablet=&#8221;28px&#8221; body_line_height_phone=&#8221;22px&#8221; body_line_height_last_edited=&#8221;on|tablet&#8221; custom_css_free_form=&#8221;selector.toggle-cus:after{||  content: %22%22;||  position: absolute;||  right: 0;||  bottom: 0%;||  height: 1px;||  background-color:rgba(0, 0, 0, 0.3);||  background-repeat: no-repeat;||  width: calc(100% &#8211; 420px);||}||selector.toggle-cus h5{||  padding-left:65px;||}||selector.toggle-cus h5:after{||   content: %22%22;||  position: absolute;||  left: 0;||  bottom: 0%;||  height: 38px;||  width:38px;||  background-repeat: no-repeat;||  background-image:url(%22https:\/\/test.irotec.nl\/wp-content\/uploads\/2025\/03\/loction-icon.png%22);||}||selector.toggle-cus.et_pb_toggle_close  {||  background-image:none;||}||selector.toggle-cus {|| padding-left: 420px;||}||selector.toggle-cus .et_pb_toggle_content{||  padding-top:10px;||}||selector.toggle-cus .et_pb_toggle_content span{||  font-size:26px;||  color:#15171E;||  font-weight:600;||}|| selector.toggle-cus .mb-img{||    display:none !important;||  }||@media(max-width:980px){||  selector.toggle-cus:before{||  width:100%;||}||selector.toggle-cus:after{||  width: 100%;||}||  selector.toggle-cus.et_pb_toggle{|| padding-left: 0px !important;||  background-image:none;||}||  selector.toggle-cus .mb-img{||    display:block !important;||  }||  selector.toggle-cus .et_pb_toggle_content{||  padding-top:20px;||}||}||&#8221; border_width_all=&#8221;0px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>iRotec bedient een breed scala aan klanten in heel Noord-Brabant, een van de meest diverse en industrieel actieve provincies van Nederland.<br \/>In Noord-Brabant werken we het meest met organisaties in de maakindustrie en industri\u00eble faciliteiten, logistiek en opslag, voedselproductie, voedselverwerking en -verpakking, retail en winkelcentra, kantoren, gezondheidszorg en vastgoedbeheer.<\/p>\n<p>Vanwege de hoge bevolkingsdichtheid, industri\u00eble activiteit en seizoensgebonden temperatuurschommelingen in de provincie omvatten veelvoorkomende plaagdieruitdagingen mieren, vliegen, vlooien, evenals ratten en muizen, vooral tijdens het najaar en de winter. De toenemende resistentie tegen traditionele bestrijdingsmethoden maakt een slimme, ge\u00efntegreerde aanpak van plaagdierbeheer (IPM) hier bijzonder belangrijk. <\/p>\n<p>Onze teams zijn actief in Eindhoven, Tilburg, Breda, &#8216;s-Hertogenbosch, Helmond, Oss, Roosendaal, Bergen op Zoom, Waalwijk, Oosterhout, Veghel, Uden en nabijgelegen steden en dorpen.<\/p>\n<p>[\/et_pb_toggle][et_pb_toggle title=&#8221;Limburg&#8221; open_toggle_text_color=&#8221;#15171e&#8221; open_toggle_background_color=&#8221;RGBA(255,255,255,0)&#8221; closed_toggle_background_color=&#8221;RGBA(255,255,255,0)&#8221; icon_color=&#8221;#000000&#8243; toggle_icon=&#8221;&#xf063;||fa||900&#8243; use_icon_font_size=&#8221;on&#8221; open_icon_color=&#8221;#000000&#8243; open_toggle_icon=&#8221;&#xf062;||fa||900&#8243; open_use_icon_font_size=&#8221;on&#8221; module_class=&#8221;toggle-cus&#8221; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; title_text_color=&#8221;#15171e&#8221; title_font=&#8221;Host Grotesk|600|||||||&#8221; title_font_size=&#8221;28px&#8221; title_line_height=&#8221;36px&#8221; body_font=&#8221;Host Grotesk||||||||&#8221; body_text_color=&#8221;#15171e&#8221; body_font_size=&#8221;18px&#8221; body_line_height=&#8221;30px&#8221; custom_margin=&#8221;||0px||false|false&#8221; custom_padding=&#8221;32px||32px||false|false&#8221; title_font_size_tablet=&#8221;28px&#8221; title_font_size_phone=&#8221;24px&#8221; title_font_size_last_edited=&#8221;on|desktop&#8221; title_line_height_tablet=&#8221;30px&#8221; title_line_height_phone=&#8221;28px&#8221; title_line_height_last_edited=&#8221;on|tablet&#8221; body_font_size_tablet=&#8221;18px&#8221; body_font_size_phone=&#8221;16px&#8221; body_font_size_last_edited=&#8221;on|phone&#8221; body_line_height_tablet=&#8221;28px&#8221; body_line_height_phone=&#8221;22px&#8221; body_line_height_last_edited=&#8221;on|tablet&#8221; custom_css_free_form=&#8221;selector.toggle-cus:after{||  content: %22%22;||  position: absolute;||  right: 0;||  bottom: 0%;||  height: 1px;||  background-color:rgba(0, 0, 0, 0.3);||  background-repeat: no-repeat;||  width: calc(100% &#8211; 420px);||}||selector.toggle-cus h5{||  padding-left:65px;||}||selector.toggle-cus h5:after{||   content: %22%22;||  position: absolute;||  left: 0;||  bottom: 0%;||  height: 38px;||  width:38px;||  background-repeat: no-repeat;||  background-image:url(%22https:\/\/test.irotec.nl\/wp-content\/uploads\/2025\/03\/loction-icon.png%22);||}||selector.toggle-cus.et_pb_toggle_close  {||  background-image:none;||}||selector.toggle-cus {|| padding-left: 420px;||}||selector.toggle-cus .et_pb_toggle_content{||  padding-top:10px;||}||selector.toggle-cus .et_pb_toggle_content span{||  font-size:26px;||  color:#15171E;||  font-weight:600;||}|| selector.toggle-cus .mb-img{||    display:none !important;||  }||@media(max-width:980px){||  selector.toggle-cus:before{||  width:100%;||}||selector.toggle-cus:after{||  width: 100%;||}||  selector.toggle-cus.et_pb_toggle{|| padding-left: 0px !important;||  background-image:none;||}||  selector.toggle-cus .mb-img{||    display:block !important;||  }||  selector.toggle-cus .et_pb_toggle_content{||  padding-top:20px;||}||}||&#8221; border_width_all=&#8221;0px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p class=\"isSelectedEnd\">Hoewel wij nog niet actief zijn in Limburg, maakt uitbreiding naar de provincie deel uit van onze toekomstige groeiplannen. Wij hopen de komende jaren ongediertebestrijdingsdiensten in heel Limburg aan te bieden en daarmee klanten te ondersteunen op locaties zoals Maastricht, Venlo, Roermond, Sittard-Geleen, Heerlen, Weert en aangrenzende gemeenten. <\/p>\n<p class=\"isSelectedEnd\">Het diverse landschap van Limburg, de grensoverschrijdende handelsactiviteit, de stedelijke centra en de uitgestrekte agrarische gebieden kunnen allemaal bijdragen aan plaaggerelateerde uitdagingen. Afhankelijk van het seizoen en de locatie kunnen problemen met knaagdieren, mieren, vliegen, wespen en andere overlastgevende plagen vaker voorkomen rond woningen, bedrijven, magazijnen en omgevingen waar met voedsel wordt gewerkt. <\/p>\n<p class=\"isSelectedEnd\">Onze toekomstige aanwezigheid in Limburg zal zich richten op het leveren van betrouwbare plaagpreventie, snelle responsdiensten en op maat gemaakte oplossingen voor zowel particuliere als zakelijke klanten. Bijzondere aandacht zal uitgaan naar sectoren waar hygi\u00ebne, naleving en operationele continu\u00efteit essentieel zijn. <\/p>\n<p>Bevindt uw pand zich in Limburg? Neem dan gerust contact met ons op en laat ons weten wat uw wensen op het gebied van ongediertebestrijding zijn. Wij houden u graag op de hoogte van de toekomstige beschikbaarheid van onze diensten. <\/p>\n<p>[\/et_pb_toggle][et_pb_toggle title=&#8221;Utrecht&#8221; open_toggle_text_color=&#8221;#15171e&#8221; open_toggle_background_color=&#8221;RGBA(255,255,255,0)&#8221; closed_toggle_background_color=&#8221;RGBA(255,255,255,0)&#8221; icon_color=&#8221;#000000&#8243; toggle_icon=&#8221;&#xf063;||fa||900&#8243; use_icon_font_size=&#8221;on&#8221; open_icon_color=&#8221;#000000&#8243; open_toggle_icon=&#8221;&#xf062;||fa||900&#8243; open_use_icon_font_size=&#8221;on&#8221; module_class=&#8221;toggle-cus&#8221; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; title_text_color=&#8221;#15171e&#8221; title_font=&#8221;Host Grotesk|600|||||||&#8221; title_font_size=&#8221;28px&#8221; title_line_height=&#8221;36px&#8221; body_font=&#8221;Host Grotesk||||||||&#8221; body_text_color=&#8221;#15171e&#8221; body_font_size=&#8221;18px&#8221; body_line_height=&#8221;30px&#8221; custom_margin=&#8221;||0px||false|false&#8221; custom_padding=&#8221;32px||32px||false|false&#8221; hover_enabled=&#8221;0&#8243; title_font_size_tablet=&#8221;28px&#8221; title_font_size_phone=&#8221;24px&#8221; title_font_size_last_edited=&#8221;on|desktop&#8221; title_line_height_tablet=&#8221;30px&#8221; title_line_height_phone=&#8221;28px&#8221; title_line_height_last_edited=&#8221;on|tablet&#8221; body_font_size_tablet=&#8221;18px&#8221; body_font_size_phone=&#8221;16px&#8221; body_font_size_last_edited=&#8221;on|phone&#8221; body_line_height_tablet=&#8221;28px&#8221; body_line_height_phone=&#8221;22px&#8221; body_line_height_last_edited=&#8221;on|tablet&#8221; custom_css_free_form=&#8221;selector.toggle-cus:after{||  content: %22%22;||  position: absolute;||  right: 0;||  bottom: 0%;||  height: 1px;||  background-color:rgba(0, 0, 0, 0.3);||  background-repeat: no-repeat;||  width: calc(100% &#8211; 420px);||}||selector.toggle-cus h5{||  padding-left:65px;||}||selector.toggle-cus h5:after{||   content: %22%22;||  position: absolute;||  left: 0;||  bottom: 0%;||  height: 38px;||  width:38px;||  background-repeat: no-repeat;||  background-image:url(%22https:\/\/test.irotec.nl\/wp-content\/uploads\/2025\/03\/loction-icon.png%22);||}||selector.toggle-cus.et_pb_toggle_close  {||  background-image:none;||}||selector.toggle-cus {|| padding-left: 420px;||}||selector.toggle-cus .et_pb_toggle_content{||  padding-top:10px;||}||selector.toggle-cus .et_pb_toggle_content span{||  font-size:26px;||  color:#15171E;||  font-weight:600;||}|| selector.toggle-cus .mb-img{||    display:none !important;||  }||@media(max-width:980px){||  selector.toggle-cus:before{||  width:100%;||}||selector.toggle-cus:after{||  width: 100%;||}||  selector.toggle-cus.et_pb_toggle{|| padding-left: 0px !important;||  background-image:none;||}||  selector.toggle-cus .mb-img{||    display:block !important;||  }||  selector.toggle-cus .et_pb_toggle_content{||  padding-top:20px;||}||}||&#8221; border_width_all=&#8221;0px&#8221; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<p>Onze specialisten in ongediertebestrijding zijn actief in de hele provincie Utrecht en ondersteunen zowel particuliere als zakelijke klanten in stedelijke, voorstedelijke en gemengde omgevingen. Wij bedienen regelmatig locaties zoals Utrecht, Amersfoort, Nieuwegein, Houten, Zeist, Woerden, Veenendaal, De Bilt, Soest, IJsselstein, Maarssen, evenals omliggende steden en dorpen. <\/p>\n<p>In Utrecht hebben plaagproblemen meestal te maken met ratten en muizen, vooral in gebieden waar voedselbronnen gemakkelijk toegankelijk zijn. Stijgende temperaturen, dichtbevolkt stedelijk wonen en voedselresten rond woningen, bedrijven en openbare ruimten dragen bij aan een toename van knaagdieractiviteit \u2014 vooral tijdens de warmere maanden. Wanneer de temperaturen dalen, trekken knaagdieren vaak naar binnen op zoek naar warmte, wat kan leiden tot verborgen besmettingen als deze niet vroegtijdig worden aangepakt.<br \/>Wij ondersteunen regelmatig klanten in sectoren zoals kantoren, detailhandel, horeca, logistiek, voedingsbedrijven, zorginstellingen, woningcorporaties en vastgoedbeheer, waar preventie, monitoring en een snelle reactie essentieel zijn om in controle en compliant te blijven.  <\/p>\n<p>Staat uw locatie er niet bij? Geen zorgen \u2014 wij bedienen ook kleinere gemeenten en landelijke gebieden in heel Utrecht. Neem contact met ons op en wij bevestigen de beschikbaarheid en de meest geschikte vervolgstappen. <\/p>\n<p>[\/et_pb_toggle][et_pb_toggle title=&#8221;Gelderland&#8221; open_toggle_text_color=&#8221;#15171e&#8221; open_toggle_background_color=&#8221;RGBA(255,255,255,0)&#8221; closed_toggle_background_color=&#8221;RGBA(255,255,255,0)&#8221; icon_color=&#8221;#000000&#8243; toggle_icon=&#8221;&#xf063;||fa||900&#8243; use_icon_font_size=&#8221;on&#8221; open_icon_color=&#8221;#000000&#8243; open_toggle_icon=&#8221;&#xf062;||fa||900&#8243; open_use_icon_font_size=&#8221;on&#8221; module_class=&#8221;toggle-cus&#8221; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; title_text_color=&#8221;#15171e&#8221; title_font=&#8221;Host Grotesk|600|||||||&#8221; title_font_size=&#8221;28px&#8221; title_line_height=&#8221;36px&#8221; body_font=&#8221;Host Grotesk||||||||&#8221; body_text_color=&#8221;#15171e&#8221; body_font_size=&#8221;18px&#8221; body_line_height=&#8221;30px&#8221; custom_margin=&#8221;||0px||false|false&#8221; custom_padding=&#8221;32px||32px||false|false&#8221; title_font_size_tablet=&#8221;28px&#8221; title_font_size_phone=&#8221;24px&#8221; title_font_size_last_edited=&#8221;on|desktop&#8221; title_line_height_tablet=&#8221;30px&#8221; title_line_height_phone=&#8221;28px&#8221; title_line_height_last_edited=&#8221;on|tablet&#8221; body_font_size_tablet=&#8221;18px&#8221; body_font_size_phone=&#8221;16px&#8221; body_font_size_last_edited=&#8221;on|phone&#8221; body_line_height_tablet=&#8221;28px&#8221; body_line_height_phone=&#8221;22px&#8221; body_line_height_last_edited=&#8221;on|tablet&#8221; custom_css_free_form=&#8221;selector.toggle-cus:after{||  content: %22%22;||  position: absolute;||  right: 0;||  bottom: 0%;||  height: 1px;||  background-color:rgba(0, 0, 0, 0.3);||  background-repeat: no-repeat;||  width: calc(100% &#8211; 420px);||}||selector.toggle-cus h5{||  padding-left:65px;||}||selector.toggle-cus h5:after{||   content: %22%22;||  position: absolute;||  left: 0;||  bottom: 0%;||  height: 38px;||  width:38px;||  background-repeat: no-repeat;||  background-image:url(%22https:\/\/test.irotec.nl\/wp-content\/uploads\/2025\/03\/loction-icon.png%22);||}||selector.toggle-cus.et_pb_toggle_close  {||  background-image:none;||}||selector.toggle-cus {|| padding-left: 420px;||}||selector.toggle-cus .et_pb_toggle_content{||  padding-top:10px;||}||selector.toggle-cus .et_pb_toggle_content span{||  font-size:26px;||  color:#15171E;||  font-weight:600;||}|| selector.toggle-cus .mb-img{||    display:none !important;||  }||@media(max-width:980px){||  selector.toggle-cus:before{||  width:100%;||}||selector.toggle-cus:after{||  width: 100%;||}||  selector.toggle-cus.et_pb_toggle{|| padding-left: 0px !important;||  background-image:none;||}||  selector.toggle-cus .mb-img{||    display:block !important;||  }||  selector.toggle-cus .et_pb_toggle_content{||  padding-top:20px;||}||}||&#8221; border_width_all=&#8221;0px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p class=\"isSelectedEnd\">Wij bieden momenteel geen ongediertebestrijdingsdiensten aan in Gelderland, maar de provincie is opgenomen in onze geplande uitbreidingsstrategie. In de toekomst willen wij klanten in heel Gelderland ondersteunen, waaronder gebieden zoals Arnhem, Nijmegen, Apeldoorn, Ede, Doetinchem, Harderwijk, Zutphen en vele omliggende steden en dorpen. <\/p>\n<p class=\"isSelectedEnd\">Als grootste provincie van Nederland kent Gelderland een grote verscheidenheid aan omgevingen, van stedelijke centra en industriegebieden tot agrarische regio&#8217;s en natuurrijke gebieden. Deze uiteenlopende omstandigheden kunnen bijdragen aan verschillende vormen van ongediertedruk, waaronder knaagdieren, insecten, vliegen en seizoensgebonden ongedierteactiviteit rond woningen en bedrijfspanden. <\/p>\n<p class=\"isSelectedEnd\">Wanneer onze diensten in Gelderland beschikbaar komen, willen wij huiseigenaren, ondernemingen, vastgoedbeheerders, logistieke faciliteiten, horecagelegenheden en voedselgerelateerde organisaties bijstaan met effectieve oplossingen voor ongediertepreventie en -bestrijding.<\/p>\n<p>Bevindt u zich in Gelderland en wilt u meer horen over toekomstige beschikbaarheid van onze diensten? Neem dan contact met ons op. Wij kijken ernaar uit de provincie te bedienen als onderdeel van onze voortdurende groei. <\/p>\n<p>[\/et_pb_toggle][et_pb_toggle title=&#8221;Flevoland&#8221; open_toggle_text_color=&#8221;#15171e&#8221; open_toggle_background_color=&#8221;RGBA(255,255,255,0)&#8221; closed_toggle_background_color=&#8221;RGBA(255,255,255,0)&#8221; icon_color=&#8221;#000000&#8243; toggle_icon=&#8221;&#xf063;||fa||900&#8243; use_icon_font_size=&#8221;on&#8221; open_icon_color=&#8221;#000000&#8243; open_toggle_icon=&#8221;&#xf062;||fa||900&#8243; open_use_icon_font_size=&#8221;on&#8221; module_class=&#8221;toggle-cus&#8221; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; title_text_color=&#8221;#15171e&#8221; title_font=&#8221;Host Grotesk|600|||||||&#8221; title_font_size=&#8221;28px&#8221; title_line_height=&#8221;36px&#8221; body_font=&#8221;Host Grotesk||||||||&#8221; body_text_color=&#8221;#15171e&#8221; body_font_size=&#8221;18px&#8221; body_line_height=&#8221;30px&#8221; custom_margin=&#8221;||0px||false|false&#8221; custom_padding=&#8221;32px||32px||false|false&#8221; title_font_size_tablet=&#8221;28px&#8221; title_font_size_phone=&#8221;24px&#8221; title_font_size_last_edited=&#8221;on|desktop&#8221; title_line_height_tablet=&#8221;30px&#8221; title_line_height_phone=&#8221;28px&#8221; title_line_height_last_edited=&#8221;on|tablet&#8221; body_font_size_tablet=&#8221;18px&#8221; body_font_size_phone=&#8221;16px&#8221; body_font_size_last_edited=&#8221;on|phone&#8221; body_line_height_tablet=&#8221;28px&#8221; body_line_height_phone=&#8221;22px&#8221; body_line_height_last_edited=&#8221;on|tablet&#8221; custom_css_free_form=&#8221;selector.toggle-cus:after{||  content: %22%22;||  position: absolute;||  right: 0;||  bottom: 0%;||  height: 1px;||  background-color:rgba(0, 0, 0, 0.3);||  background-repeat: no-repeat;||  width: calc(100% &#8211; 420px);||}||selector.toggle-cus h5{||  padding-left:65px;||}||selector.toggle-cus h5:after{||   content: %22%22;||  position: absolute;||  left: 0;||  bottom: 0%;||  height: 38px;||  width:38px;||  background-repeat: no-repeat;||  background-image:url(%22https:\/\/test.irotec.nl\/wp-content\/uploads\/2025\/03\/loction-icon.png%22);||}||selector.toggle-cus.et_pb_toggle_close  {||  background-image:none;||}||selector.toggle-cus {|| padding-left: 420px;||}||selector.toggle-cus .et_pb_toggle_content{||  padding-top:10px;||}||selector.toggle-cus .et_pb_toggle_content span{||  font-size:26px;||  color:#15171E;||  font-weight:600;||}|| selector.toggle-cus .mb-img{||    display:none !important;||  }||@media(max-width:980px){||  selector.toggle-cus:before{||  width:100%;||}||selector.toggle-cus:after{||  width: 100%;||}||  selector.toggle-cus.et_pb_toggle{|| padding-left: 0px !important;||  background-image:none;||}||  selector.toggle-cus .mb-img{||    display:block !important;||  }||  selector.toggle-cus .et_pb_toggle_content{||  padding-top:20px;||}||}||&#8221; border_width_all=&#8221;0px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p class=\"isSelectedEnd\">Op dit moment bieden wij geen ongediertebestrijdingsdiensten aan in Flevoland, maar wij zijn van plan om als onderdeel van onze toekomstige ontwikkelingsplannen naar de provincie uit te breiden. Ons doel is uiteindelijk particuliere en zakelijke klanten in heel Flevoland te ondersteunen, waaronder Almere, Lelystad, Dronten, Emmeloord, Zeewolde, Urk en de omliggende gemeenschappen. <\/p>\n<p class=\"isSelectedEnd\">Het unieke landschap van Flevoland, de moderne stedelijke ontwikkelingen, de uitgebreide agrarische activiteit en de grote distributiecentra cre\u00ebren omgevingsomstandigheden die een reeks plagen kunnen aantrekken. Knaagdieren, vliegen, mieren en andere overlastgevende plagen kunnen problematisch worden wanneer voedsel, beschutting en water gemakkelijk beschikbaar zijn. <\/p>\n<p class=\"isSelectedEnd\">Naarmate ons servicenetwerk blijft groeien, streven wij ernaar professionele plaagbeheersingsoplossingen te bieden die zijn afgestemd op de behoeften van bedrijven, huiseigenaren, logistieke dienstverleners, voedselgerelateerde bedrijven en vastgoedbeheerders in de hele provincie.<\/p>\n<p>Bent u gevestigd in Flevoland en wilt u op de hoogte blijven van onze toekomstige uitbreidingsplannen? Neem dan contact met ons op. Wij stellen u graag op de hoogte zodra onze diensten in uw regio beschikbaar komen. <\/p>\n<p>[\/et_pb_toggle][et_pb_toggle title=&#8221;Overijssel&#8221; open_toggle_text_color=&#8221;#15171e&#8221; open_toggle_background_color=&#8221;RGBA(255,255,255,0)&#8221; closed_toggle_background_color=&#8221;RGBA(255,255,255,0)&#8221; icon_color=&#8221;#000000&#8243; toggle_icon=&#8221;&#xf063;||fa||900&#8243; use_icon_font_size=&#8221;on&#8221; open_icon_color=&#8221;#000000&#8243; open_toggle_icon=&#8221;&#xf062;||fa||900&#8243; open_use_icon_font_size=&#8221;on&#8221; module_class=&#8221;toggle-cus&#8221; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; title_text_color=&#8221;#15171e&#8221; title_font=&#8221;Host Grotesk|600|||||||&#8221; title_font_size=&#8221;28px&#8221; title_line_height=&#8221;36px&#8221; body_font=&#8221;Host Grotesk||||||||&#8221; body_text_color=&#8221;#15171e&#8221; body_font_size=&#8221;18px&#8221; body_line_height=&#8221;30px&#8221; custom_margin=&#8221;||0px||false|false&#8221; custom_padding=&#8221;32px||32px||false|false&#8221; title_font_size_tablet=&#8221;28px&#8221; title_font_size_phone=&#8221;24px&#8221; title_font_size_last_edited=&#8221;on|desktop&#8221; title_line_height_tablet=&#8221;30px&#8221; title_line_height_phone=&#8221;28px&#8221; title_line_height_last_edited=&#8221;on|tablet&#8221; body_font_size_tablet=&#8221;18px&#8221; body_font_size_phone=&#8221;16px&#8221; body_font_size_last_edited=&#8221;on|phone&#8221; body_line_height_tablet=&#8221;28px&#8221; body_line_height_phone=&#8221;22px&#8221; body_line_height_last_edited=&#8221;on|tablet&#8221; custom_css_free_form=&#8221;selector.toggle-cus:after{||  content: %22%22;||  position: absolute;||  right: 0;||  bottom: 0%;||  height: 1px;||  background-color:rgba(0, 0, 0, 0.3);||  background-repeat: no-repeat;||  width: calc(100% &#8211; 420px);||}||selector.toggle-cus h5{||  padding-left:65px;||}||selector.toggle-cus h5:after{||   content: %22%22;||  position: absolute;||  left: 0;||  bottom: 0%;||  height: 38px;||  width:38px;||  background-repeat: no-repeat;||  background-image:url(%22https:\/\/test.irotec.nl\/wp-content\/uploads\/2025\/03\/loction-icon.png%22);||}||selector.toggle-cus.et_pb_toggle_close  {||  background-image:none;||}||selector.toggle-cus {|| padding-left: 420px;||}||selector.toggle-cus .et_pb_toggle_content{||  padding-top:10px;||}||selector.toggle-cus .et_pb_toggle_content span{||  font-size:26px;||  color:#15171E;||  font-weight:600;||}|| selector.toggle-cus .mb-img{||    display:none !important;||  }||@media(max-width:980px){||  selector.toggle-cus:before{||  width:100%;||}||selector.toggle-cus:after{||  width: 100%;||}||  selector.toggle-cus.et_pb_toggle{|| padding-left: 0px !important;||  background-image:none;||}||  selector.toggle-cus .mb-img{||    display:block !important;||  }||  selector.toggle-cus .et_pb_toggle_content{||  padding-top:20px;||}||}||&#8221; border_width_all=&#8221;0px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p class=\"isSelectedEnd\">Hoewel wij momenteel niet actief zijn in Overijssel, zijn wij van plan onze ongediertebestrijdingsdiensten in de toekomst naar de provincie uit te breiden. Wij hopen klanten in de hele regio te bedienen, waaronder Zwolle, Enschede, Deventer, Hengelo, Almelo, Kampen, Oldenzaal en nabijgelegen steden en landelijke gebieden. <\/p>\n<p class=\"isSelectedEnd\">Overijssel combineert groeiende stedelijke centra met landbouwgrond, industrieterreinen en transportcorridors. Deze diverse omgevingen kunnen bijdragen aan uiteenlopende ongedierteproblemen, vari\u00ebrend van knaagdieractiviteit in magazijnen en bedrijfsgebouwen tot insectgerelateerde problemen in woon- en horecaomgevingen. <\/p>\n<p class=\"isSelectedEnd\">Onze toekomstige diensten in Overijssel zullen zich richten op praktisch ongediertebeheer op lange termijn, waarbij wij ondernemingen en huiseigenaren helpen risico&#8217;s te verminderen en tegelijkertijd veilige en hygi\u00ebnische omgevingen te behouden. Wij begrijpen het belang van preventie, snelle interventie en compliancy voor veel sectoren die binnen de provincie actief zijn. <\/p>\n<p>Bevindt u zich in Overijssel en bent u ge\u00efnteresseerd in onze toekomstige beschikbaarheid? Dan nodigen wij u graag uit om contact met ons op te nemen en uw interesse kenbaar te maken.<\/p>\n<p>[\/et_pb_toggle][et_pb_toggle title=&#8221;Drenthe&#8221; open_toggle_text_color=&#8221;#15171e&#8221; open_toggle_background_color=&#8221;RGBA(255,255,255,0)&#8221; closed_toggle_background_color=&#8221;RGBA(255,255,255,0)&#8221; icon_color=&#8221;#000000&#8243; toggle_icon=&#8221;&#xf063;||fa||900&#8243; use_icon_font_size=&#8221;on&#8221; open_icon_color=&#8221;#000000&#8243; open_toggle_icon=&#8221;&#xf062;||fa||900&#8243; open_use_icon_font_size=&#8221;on&#8221; module_class=&#8221;toggle-cus&#8221; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; title_text_color=&#8221;#15171e&#8221; title_font=&#8221;Host Grotesk|600|||||||&#8221; title_font_size=&#8221;28px&#8221; title_line_height=&#8221;36px&#8221; body_font=&#8221;Host Grotesk||||||||&#8221; body_text_color=&#8221;#15171e&#8221; body_font_size=&#8221;18px&#8221; body_line_height=&#8221;30px&#8221; custom_margin=&#8221;||0px||false|false&#8221; custom_padding=&#8221;32px||32px||false|false&#8221; title_font_size_tablet=&#8221;28px&#8221; title_font_size_phone=&#8221;24px&#8221; title_font_size_last_edited=&#8221;on|desktop&#8221; title_line_height_tablet=&#8221;30px&#8221; title_line_height_phone=&#8221;28px&#8221; title_line_height_last_edited=&#8221;on|tablet&#8221; body_font_size_tablet=&#8221;18px&#8221; body_font_size_phone=&#8221;16px&#8221; body_font_size_last_edited=&#8221;on|phone&#8221; body_line_height_tablet=&#8221;28px&#8221; body_line_height_phone=&#8221;22px&#8221; body_line_height_last_edited=&#8221;on|tablet&#8221; custom_css_free_form=&#8221;selector.toggle-cus:after{||  content: %22%22;||  position: absolute;||  right: 0;||  bottom: 0%;||  height: 1px;||  background-color:rgba(0, 0, 0, 0.3);||  background-repeat: no-repeat;||  width: calc(100% &#8211; 420px);||}||selector.toggle-cus h5{||  padding-left:65px;||}||selector.toggle-cus h5:after{||   content: %22%22;||  position: absolute;||  left: 0;||  bottom: 0%;||  height: 38px;||  width:38px;||  background-repeat: no-repeat;||  background-image:url(%22https:\/\/test.irotec.nl\/wp-content\/uploads\/2025\/03\/loction-icon.png%22);||}||selector.toggle-cus.et_pb_toggle_close  {||  background-image:none;||}||selector.toggle-cus {|| padding-left: 420px;||}||selector.toggle-cus .et_pb_toggle_content{||  padding-top:10px;||}||selector.toggle-cus .et_pb_toggle_content span{||  font-size:26px;||  color:#15171E;||  font-weight:600;||}|| selector.toggle-cus .mb-img{||    display:none !important;||  }||@media(max-width:980px){||  selector.toggle-cus:before{||  width:100%;||}||selector.toggle-cus:after{||  width: 100%;||}||  selector.toggle-cus.et_pb_toggle{|| padding-left: 0px !important;||  background-image:none;||}||  selector.toggle-cus .mb-img{||    display:block !important;||  }||  selector.toggle-cus .et_pb_toggle_content{||  padding-top:20px;||}||}||&#8221; border_width_all=&#8221;0px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p class=\"isSelectedEnd\">Wij bieden momenteel geen diensten voor ongediertebestrijding in Drenthe aan, hoewel de provincie is opgenomen in onze langetermijnplannen voor uitbreiding. Naarmate ons werkgebied groeit, streven we ernaar klanten te ondersteunen in Assen, Emmen, Hoogeveen, Meppel, Coevorden en andere gemeenschappen in de regio. <\/p>\n<p class=\"isSelectedEnd\">Drenthe staat bekend om zijn landelijke karakter, landbouwactiviteit, natuurlijke landschappen en groeiende bedrijfssectoren. Deze omstandigheden kunnen mogelijkheden cre\u00ebren voor plaagdieren zoals knaagdieren, mieren, vliegen en seizoensgebonden insecten om zich te vestigen rond woningen, boerderijen, bedrijfspanden en opslagfaciliteiten. <\/p>\n<p class=\"isSelectedEnd\">Met het oog op de toekomst is het ons doel om effectieve diensten voor plaagpreventie en -bestrijding te leveren die voldoen aan de behoeften van zowel particuliere als zakelijke klanten. We zijn van plan oplossingen te bieden die zijn ontworpen om verstoring tot een minimum te beperken en klanten tegelijkertijd te helpen een gezonde en goed beschermde omgeving te behouden. <\/p>\n<p>Als u in Drenthe gevestigd bent en updates wilt ontvangen over de toekomstige beschikbaarheid van onze diensten, neem dan gerust contact op met ons team.<\/p>\n<p>[\/et_pb_toggle][et_pb_toggle title=&#8221;Friesland&#8221; open_toggle_text_color=&#8221;#15171e&#8221; open_toggle_background_color=&#8221;RGBA(255,255,255,0)&#8221; closed_toggle_background_color=&#8221;RGBA(255,255,255,0)&#8221; icon_color=&#8221;#000000&#8243; toggle_icon=&#8221;&#xf063;||fa||900&#8243; use_icon_font_size=&#8221;on&#8221; open_icon_color=&#8221;#000000&#8243; open_toggle_icon=&#8221;&#xf062;||fa||900&#8243; open_use_icon_font_size=&#8221;on&#8221; module_class=&#8221;toggle-cus&#8221; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; title_text_color=&#8221;#15171e&#8221; title_font=&#8221;Host Grotesk|600|||||||&#8221; title_font_size=&#8221;28px&#8221; title_line_height=&#8221;36px&#8221; body_font=&#8221;Host Grotesk||||||||&#8221; body_text_color=&#8221;#15171e&#8221; body_font_size=&#8221;18px&#8221; body_line_height=&#8221;30px&#8221; custom_margin=&#8221;||0px||false|false&#8221; custom_padding=&#8221;32px||32px||false|false&#8221; title_font_size_tablet=&#8221;28px&#8221; title_font_size_phone=&#8221;24px&#8221; title_font_size_last_edited=&#8221;on|desktop&#8221; title_line_height_tablet=&#8221;30px&#8221; title_line_height_phone=&#8221;28px&#8221; title_line_height_last_edited=&#8221;on|tablet&#8221; body_font_size_tablet=&#8221;18px&#8221; body_font_size_phone=&#8221;16px&#8221; body_font_size_last_edited=&#8221;on|phone&#8221; body_line_height_tablet=&#8221;28px&#8221; body_line_height_phone=&#8221;22px&#8221; body_line_height_last_edited=&#8221;on|tablet&#8221; custom_css_free_form=&#8221;selector.toggle-cus:after{||  content: %22%22;||  position: absolute;||  right: 0;||  bottom: 0%;||  height: 1px;||  background-color:rgba(0, 0, 0, 0.3);||  background-repeat: no-repeat;||  width: calc(100% &#8211; 420px);||}||selector.toggle-cus h5{||  padding-left:65px;||}||selector.toggle-cus h5:after{||   content: %22%22;||  position: absolute;||  left: 0;||  bottom: 0%;||  height: 38px;||  width:38px;||  background-repeat: no-repeat;||  background-image:url(%22https:\/\/test.irotec.nl\/wp-content\/uploads\/2025\/03\/loction-icon.png%22);||}||selector.toggle-cus.et_pb_toggle_close  {||  background-image:none;||}||selector.toggle-cus {|| padding-left: 420px;||}||selector.toggle-cus .et_pb_toggle_content{||  padding-top:10px;||}||selector.toggle-cus .et_pb_toggle_content span{||  font-size:26px;||  color:#15171E;||  font-weight:600;||}|| selector.toggle-cus .mb-img{||    display:none !important;||  }||@media(max-width:980px){||  selector.toggle-cus:before{||  width:100%;||}||selector.toggle-cus:after{||  width: 100%;||}||  selector.toggle-cus.et_pb_toggle{|| padding-left: 0px !important;||  background-image:none;||}||  selector.toggle-cus .mb-img{||    display:block !important;||  }||  selector.toggle-cus .et_pb_toggle_content{||  padding-top:20px;||}||}||&#8221; border_width_all=&#8221;0px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p class=\"isSelectedEnd\">Hoewel wij nog niet actief zijn in Friesland, onderzoeken wij mogelijkheden om onze ongediertebestrijdingsdiensten in de toekomst naar de provincie te brengen. Onze ambitie is om klanten in heel Friesland te ondersteunen, waaronder Leeuwarden, Drachten, Heerenveen, Sneek, Harlingen, Franeker en de omliggende steden en dorpen. <\/p>\n<p class=\"isSelectedEnd\">De mix van landbouwgrond, waterwegen, toerisme en woningbouw in Friesland kan bijdragen aan uiteenlopende ongediertegerelateerde uitdagingen. Knaagdieren, vliegende insecten, mieren en ander overlastgevend ongedierte kunnen, afhankelijk van seizoensgebonden omstandigheden en lokale milieufactoren, steeds actiever worden. <\/p>\n<p class=\"isSelectedEnd\">Wanneer wij uitbreiden naar Friesland, zijn wij voornemens op maat gemaakte oplossingen voor ongediertebeheer te bieden voor huiseigenaren, horecabedrijven, agrarische ondernemingen, kantoren, winkellocaties en vastgoedbeheerorganisaties. Onze aanpak zal zich richten op preventie, monitoring en effectieve langetermijnbeheersing. <\/p>\n<p>Als uw pand in Friesland is gelegen, moedigen wij u aan contact met ons op te nemen en ons uw wensen kenbaar te maken. Wij houden u graag op de hoogte van toekomstige ontwikkelingen. <\/p>\n<p>[\/et_pb_toggle][et_pb_toggle title=&#8221;Groningen&#8221; open_toggle_text_color=&#8221;#15171e&#8221; open_toggle_background_color=&#8221;RGBA(255,255,255,0)&#8221; closed_toggle_background_color=&#8221;RGBA(255,255,255,0)&#8221; icon_color=&#8221;#000000&#8243; toggle_icon=&#8221;&#xf063;||fa||900&#8243; use_icon_font_size=&#8221;on&#8221; open_icon_color=&#8221;#000000&#8243; open_toggle_icon=&#8221;&#xf062;||fa||900&#8243; open_use_icon_font_size=&#8221;on&#8221; module_class=&#8221;toggle-cus&#8221; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; title_text_color=&#8221;#15171e&#8221; title_font=&#8221;Host Grotesk|600|||||||&#8221; title_font_size=&#8221;28px&#8221; title_line_height=&#8221;36px&#8221; body_font=&#8221;Host Grotesk||||||||&#8221; body_text_color=&#8221;#15171e&#8221; body_font_size=&#8221;18px&#8221; body_line_height=&#8221;30px&#8221; custom_margin=&#8221;||0px||false|false&#8221; custom_padding=&#8221;32px||32px||false|false&#8221; title_font_size_tablet=&#8221;28px&#8221; title_font_size_phone=&#8221;24px&#8221; title_font_size_last_edited=&#8221;on|desktop&#8221; title_line_height_tablet=&#8221;30px&#8221; title_line_height_phone=&#8221;28px&#8221; title_line_height_last_edited=&#8221;on|tablet&#8221; body_font_size_tablet=&#8221;18px&#8221; body_font_size_phone=&#8221;16px&#8221; body_font_size_last_edited=&#8221;on|phone&#8221; body_line_height_tablet=&#8221;28px&#8221; body_line_height_phone=&#8221;22px&#8221; body_line_height_last_edited=&#8221;on|tablet&#8221; custom_css_free_form=&#8221;selector.toggle-cus:after{||  content: %22%22;||  position: absolute;||  right: 0;||  bottom: 0%;||  height: 1px;||  background-color:rgba(0, 0, 0, 0.3);||  background-repeat: no-repeat;||  width: calc(100% &#8211; 420px);||}||selector.toggle-cus h5{||  padding-left:65px;||}||selector.toggle-cus h5:after{||   content: %22%22;||  position: absolute;||  left: 0;||  bottom: 0%;||  height: 38px;||  width:38px;||  background-repeat: no-repeat;||  background-image:url(%22https:\/\/test.irotec.nl\/wp-content\/uploads\/2025\/03\/loction-icon.png%22);||}||selector.toggle-cus.et_pb_toggle_close  {||  background-image:none;||}||selector.toggle-cus {|| padding-left: 420px;||}||selector.toggle-cus .et_pb_toggle_content{||  padding-top:10px;||}||selector.toggle-cus .et_pb_toggle_content span{||  font-size:26px;||  color:#15171E;||  font-weight:600;||}|| selector.toggle-cus .mb-img{||    display:none !important;||  }||@media(max-width:980px){||  selector.toggle-cus:before{||  width:100%;||}||selector.toggle-cus:after{||  width: 100%;||}||  selector.toggle-cus.et_pb_toggle{|| padding-left: 0px !important;||  background-image:none;||}||  selector.toggle-cus .mb-img{||    display:block !important;||  }||  selector.toggle-cus .et_pb_toggle_content{||  padding-top:20px;||}||}||&#8221; border_width_all=&#8221;0px&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p class=\"isSelectedEnd\">Wij bieden momenteel geen diensten voor ongediertebestrijding aan in Groningen, maar de provincie maakt deel uit van onze geplande toekomstige uitbreiding. Naarmate wij blijven groeien, hopen wij onze diensten beschikbaar te maken voor klanten in heel Groningen, waaronder de stad Groningen, Winschoten, Veendam, Hoogezand, Delfzijl, Stadskanaal en omliggende gebieden. <\/p>\n<p class=\"isSelectedEnd\">De combinatie van stedelijke wijken, industri\u00eble activiteit, havens, agrarische regio&#8217;s en woongemeenschappen in Groningen kan gunstige omstandigheden cre\u00ebren voor diverse plagen. Knaagdieren, vliegen, mieren en andere plaagsoorten kunnen een probleem worden wanneer er geschikte voedselbronnen en beschutting aanwezig zijn. <\/p>\n<p class=\"isSelectedEnd\">Ons toekomstige doel is om betrouwbare diensten voor ongediertebestrijding en preventie te bieden die bedrijven en huiseigenaren helpen hun panden te beschermen en veilige, hygi\u00ebnische omgevingen te behouden. Wij streven er met name naar sectoren te ondersteunen waar plaagbeheersing een belangrijke rol speelt in operationele continu\u00efteit en naleving van regelgeving. <\/p>\n<p>Bent u gevestigd in Groningen en wilt u weten wanneer onze diensten beschikbaar komen? Neem dan contact met ons op. Wij kijken ernaar uit om in de toekomst uit te breiden naar de provincie. <\/p>\n<p>[\/et_pb_toggle][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wij bieden met trots deskundige ongediertebestrijdingsoplossingen aan op meerdere locaties. Ontdek hoe wij kunnen helpen om uw huis of bedrijf in uw regio vrij van ongedierte te houden.Bekijk de regio\u2019s waar wij actief zijnBekijk de regio\u2019s waar wij actief zijnOnze technici staan voor u klaar in de volgende regio\u2019sProvinciesOnze ongediertebestrijdingsspecialisten zijn actief in heel Noord-Holland [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-4545","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Locaties - irotec.wisefrog.eu<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/test.irotec.nl\/nl\/regios\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Locaties - irotec.wisefrog.eu\" \/>\n<meta property=\"og:description\" content=\"Wij bieden met trots deskundige ongediertebestrijdingsoplossingen aan op meerdere locaties. Ontdek hoe wij kunnen helpen om uw huis of bedrijf in uw regio vrij van ongedierte te houden.Bekijk de regio\u2019s waar wij actief zijnBekijk de regio\u2019s waar wij actief zijnOnze technici staan voor u klaar in de volgende regio\u2019sProvinciesOnze ongediertebestrijdingsspecialisten zijn actief in heel Noord-Holland [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/test.irotec.nl\/nl\/regios\/\" \/>\n<meta property=\"og:site_name\" content=\"irotec.wisefrog.eu\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-25T11:45:23+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschatte leestijd\" \/>\n\t<meta name=\"twitter:data1\" content=\"41 minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/test.irotec.nl\\\/nl\\\/regios\\\/\",\"url\":\"https:\\\/\\\/test.irotec.nl\\\/nl\\\/regios\\\/\",\"name\":\"Locaties - irotec.wisefrog.eu\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/test.irotec.nl\\\/nl\\\/#website\"},\"datePublished\":\"2025-03-05T09:20:12+00:00\",\"dateModified\":\"2026-06-25T11:45:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/test.irotec.nl\\\/nl\\\/regios\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/test.irotec.nl\\\/nl\\\/regios\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/test.irotec.nl\\\/nl\\\/regios\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/test.irotec.nl\\\/nl\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Locaties\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/test.irotec.nl\\\/nl\\\/#website\",\"url\":\"https:\\\/\\\/test.irotec.nl\\\/nl\\\/\",\"name\":\"iRotec Pest Control\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/test.irotec.nl\\\/nl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/test.irotec.nl\\\/nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/test.irotec.nl\\\/nl\\\/#organization\",\"name\":\"iRotec Pest Control\",\"url\":\"https:\\\/\\\/test.irotec.nl\\\/nl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/test.irotec.nl\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/test.irotec.nl\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/header-logo.png\",\"contentUrl\":\"https:\\\/\\\/test.irotec.nl\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/header-logo.png\",\"width\":250,\"height\":84,\"caption\":\"iRotec Pest Control\"},\"image\":{\"@id\":\"https:\\\/\\\/test.irotec.nl\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Locaties - irotec.wisefrog.eu","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/test.irotec.nl\/nl\/regios\/","og_locale":"nl_NL","og_type":"article","og_title":"Locaties - irotec.wisefrog.eu","og_description":"Wij bieden met trots deskundige ongediertebestrijdingsoplossingen aan op meerdere locaties. Ontdek hoe wij kunnen helpen om uw huis of bedrijf in uw regio vrij van ongedierte te houden.Bekijk de regio\u2019s waar wij actief zijnBekijk de regio\u2019s waar wij actief zijnOnze technici staan voor u klaar in de volgende regio\u2019sProvinciesOnze ongediertebestrijdingsspecialisten zijn actief in heel Noord-Holland [&hellip;]","og_url":"https:\/\/test.irotec.nl\/nl\/regios\/","og_site_name":"irotec.wisefrog.eu","article_modified_time":"2026-06-25T11:45:23+00:00","twitter_card":"summary_large_image","twitter_misc":{"Geschatte leestijd":"41 minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/test.irotec.nl\/nl\/regios\/","url":"https:\/\/test.irotec.nl\/nl\/regios\/","name":"Locaties - irotec.wisefrog.eu","isPartOf":{"@id":"https:\/\/test.irotec.nl\/nl\/#website"},"datePublished":"2025-03-05T09:20:12+00:00","dateModified":"2026-06-25T11:45:23+00:00","breadcrumb":{"@id":"https:\/\/test.irotec.nl\/nl\/regios\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/test.irotec.nl\/nl\/regios\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/test.irotec.nl\/nl\/regios\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/test.irotec.nl\/nl\/home\/"},{"@type":"ListItem","position":2,"name":"Locaties"}]},{"@type":"WebSite","@id":"https:\/\/test.irotec.nl\/nl\/#website","url":"https:\/\/test.irotec.nl\/nl\/","name":"iRotec Pest Control","description":"","publisher":{"@id":"https:\/\/test.irotec.nl\/nl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/test.irotec.nl\/nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/test.irotec.nl\/nl\/#organization","name":"iRotec Pest Control","url":"https:\/\/test.irotec.nl\/nl\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/test.irotec.nl\/nl\/#\/schema\/logo\/image\/","url":"https:\/\/test.irotec.nl\/wp-content\/uploads\/2025\/03\/header-logo.png","contentUrl":"https:\/\/test.irotec.nl\/wp-content\/uploads\/2025\/03\/header-logo.png","width":250,"height":84,"caption":"iRotec Pest Control"},"image":{"@id":"https:\/\/test.irotec.nl\/nl\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/test.irotec.nl\/nl\/wp-json\/wp\/v2\/pages\/4545","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/test.irotec.nl\/nl\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/test.irotec.nl\/nl\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/test.irotec.nl\/nl\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/test.irotec.nl\/nl\/wp-json\/wp\/v2\/comments?post=4545"}],"version-history":[{"count":12,"href":"https:\/\/test.irotec.nl\/nl\/wp-json\/wp\/v2\/pages\/4545\/revisions"}],"predecessor-version":[{"id":5803,"href":"https:\/\/test.irotec.nl\/nl\/wp-json\/wp\/v2\/pages\/4545\/revisions\/5803"}],"wp:attachment":[{"href":"https:\/\/test.irotec.nl\/nl\/wp-json\/wp\/v2\/media?parent=4545"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}